{"id":1485,"count":1,"description":"","link":"https:\/\/bbr.news\/en\/tag\/airtracker-en","name":"Airtracker","slug":"airtracker-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Airtracker Archive - bbr B\u00e4nder Bleche Rohre<\/title>\n<meta name=\"description\" content=\"Airtracker\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bbr.news\/en\/tag\/airtracker-en\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Airtracker Archive - bbr B\u00e4nder Bleche Rohre\" \/>\n<meta property=\"og:description\" content=\"Airtracker\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bbr.news\/en\/tag\/airtracker-en\" \/>\n<meta property=\"og:site_name\" content=\"bbr B\u00e4nder Bleche Rohre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/bbr.news\/en\/tag\/airtracker-en\",\"url\":\"https:\/\/bbr.news\/en\/tag\/airtracker-en\",\"name\":\"Airtracker Archive - bbr B\u00e4nder Bleche Rohre\",\"isPartOf\":{\"@id\":\"https:\/\/bbr.news\/en#website\"},\"description\":\"Airtracker\",\"breadcrumb\":{\"@id\":\"https:\/\/bbr.news\/en\/tag\/airtracker-en#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bbr.news\/en\/tag\/airtracker-en#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\/\/bbr.news\/en\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Airtracker\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bbr.news\/en#website\",\"url\":\"https:\/\/bbr.news\/en\",\"name\":\"bbr B\u00e4nder Bleche Rohre\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/bbr.news\/en#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bbr.news\/en?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/bbr.news\/en#organization\",\"name\":\"TS MediaConsult\",\"url\":\"https:\/\/bbr.news\/en\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/bbr.news\/en#\/schema\/logo\/image\/\",\"url\":\"https:\/\/bbr.news\/wp-content\/uploads\/2021\/08\/cropped-logobrowserbbr.png\",\"contentUrl\":\"https:\/\/bbr.news\/wp-content\/uploads\/2021\/08\/cropped-logobrowserbbr.png\",\"width\":512,\"height\":512,\"caption\":\"TS MediaConsult\"},\"image\":{\"@id\":\"https:\/\/bbr.news\/en#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/bbr-baender-bleche-rohre\",\"https:\/\/www.youtube.com\/channel\/UCH05KnFDaqGAKUPkldd0myQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Airtracker Archive - bbr B\u00e4nder Bleche Rohre","description":"Airtracker","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bbr.news\/en\/tag\/airtracker-en","og_locale":"en_US","og_type":"article","og_title":"Airtracker Archive - bbr B\u00e4nder Bleche Rohre","og_description":"Airtracker","og_url":"https:\/\/bbr.news\/en\/tag\/airtracker-en","og_site_name":"bbr B\u00e4nder Bleche Rohre","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/bbr.news\/en\/tag\/airtracker-en","url":"https:\/\/bbr.news\/en\/tag\/airtracker-en","name":"Airtracker Archive - bbr B\u00e4nder Bleche Rohre","isPartOf":{"@id":"https:\/\/bbr.news\/en#website"},"description":"Airtracker","breadcrumb":{"@id":"https:\/\/bbr.news\/en\/tag\/airtracker-en#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/bbr.news\/en\/tag\/airtracker-en#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/bbr.news\/en"},{"@type":"ListItem","position":2,"name":"Airtracker"}]},{"@type":"WebSite","@id":"https:\/\/bbr.news\/en#website","url":"https:\/\/bbr.news\/en","name":"bbr B\u00e4nder Bleche Rohre","description":"","publisher":{"@id":"https:\/\/bbr.news\/en#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bbr.news\/en?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/bbr.news\/en#organization","name":"TS MediaConsult","url":"https:\/\/bbr.news\/en","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bbr.news\/en#\/schema\/logo\/image\/","url":"https:\/\/bbr.news\/wp-content\/uploads\/2021\/08\/cropped-logobrowserbbr.png","contentUrl":"https:\/\/bbr.news\/wp-content\/uploads\/2021\/08\/cropped-logobrowserbbr.png","width":512,"height":512,"caption":"TS MediaConsult"},"image":{"@id":"https:\/\/bbr.news\/en#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/bbr-baender-bleche-rohre","https:\/\/www.youtube.com\/channel\/UCH05KnFDaqGAKUPkldd0myQ"]}]}},"_links":{"self":[{"href":"https:\/\/bbr.news\/en\/wp-json\/wp\/v2\/tags\/1485"}],"collection":[{"href":"https:\/\/bbr.news\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/bbr.news\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/bbr.news\/en\/wp-json\/wp\/v2\/posts?tags=1485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}